<br />
<b>Deprecated</b>:  Optional parameter $i declared before required parameter $post_id is implicitly treated as a required parameter in <b>/var/www/vhosts/kultur-radolfzell.de/staging.kultur-radolfzell.de/wp-content/plugins/advanced-custom-fields-pro-2/pro/fields/class-acf-field-repeater.php</b> on line <b>720</b><br />
<br />
<b>Deprecated</b>:  Optional parameter $i declared before required parameter $post_id is implicitly treated as a required parameter in <b>/var/www/vhosts/kultur-radolfzell.de/staging.kultur-radolfzell.de/wp-content/plugins/advanced-custom-fields-pro-2/pro/fields/class-acf-field-repeater.php</b> on line <b>786</b><br />
<br />
<b>Deprecated</b>:  Optional parameter $name declared before required parameter $field is implicitly treated as a required parameter in <b>/var/www/vhosts/kultur-radolfzell.de/staging.kultur-radolfzell.de/wp-content/plugins/advanced-custom-fields-pro-2/pro/fields/class-acf-field-flexible-content.php</b> on line <b>1038</b><br />
<br />
<b>Deprecated</b>:  Optional parameter $i declared before required parameter $post_id is implicitly treated as a required parameter in <b>/var/www/vhosts/kultur-radolfzell.de/staging.kultur-radolfzell.de/wp-content/plugins/advanced-custom-fields-pro-2/pro/fields/class-acf-field-flexible-content.php</b> on line <b>1074</b><br />
<br />
<b>Deprecated</b>:  Optional parameter $i declared before required parameter $post_id is implicitly treated as a required parameter in <b>/var/www/vhosts/kultur-radolfzell.de/staging.kultur-radolfzell.de/wp-content/plugins/advanced-custom-fields-pro-2/pro/fields/class-acf-field-flexible-content.php</b> on line <b>1126</b><br />
<br />
<b>Deprecated</b>:  Optional parameter $id declared before required parameter $field is implicitly treated as a required parameter in <b>/var/www/vhosts/kultur-radolfzell.de/staging.kultur-radolfzell.de/wp-content/plugins/advanced-custom-fields-pro-2/pro/fields/class-acf-field-gallery.php</b> on line <b>302</b><br />
{"id":80508,"date":"2024-04-26T11:06:20","date_gmt":"2024-04-26T09:06:20","guid":{"rendered":"https:\/\/kultur-radolfzell.de\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/"},"modified":"2024-04-26T11:06:20","modified_gmt":"2024-04-26T09:06:20","slug":"mundstuhl-peut-contenir-des-traces-de-noix-34","status":"publish","type":"tribe_events","link":"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/","title":{"rendered":"Mundstuhl &#8211; Peut contenir des traces de noix"},"content":{"rendered":"<p>Le meilleur duo comique de l&rsquo;univers sort son prochain coup !<br \/>\nEt oui ! Ce sera plus dr\u00f4le que jamais. Si vous pensiez avoir atteint le sommet de la folie humoristique apr\u00e8s 25 ans de MUNDSTUHL, le tout nouveau programme KANN SPUREN VON N\u00dcSSEN ENTHALTEN vous fera changer d&rsquo;avis.<\/p>\n<p>Si frais et vari\u00e9, si d\u00e9jant\u00e9 et rapide, comme si les deux sympathiques laur\u00e9ats de l&rsquo;Echopreis s&rsquo;\u00e9taient inject\u00e9 une dose d&rsquo;adr\u00e9naline dans le centre de l&rsquo;humour v\u00e9g\u00e9tatif. Dans le plus pur style Mundstuhl, des personnages chers \u00e0 l&rsquo;auteur mais aussi des personnages tout neufs se donnent la r\u00e9plique sur sc\u00e8ne. Le psychopathe Grillschorsch, le col\u00e9rique Andi, les activistes pacifistes sans pression Malte et Torben de No Pressure et, en tant qu&rsquo;invit\u00e9 sp\u00e9cial, Der Dschieses, qui est de retour sur terre sur l&rsquo;ordre de son p\u00e8re &#8211; tous les personnages de Mundstuhl ont un s\u00e9rieux probl\u00e8me et sont con\u00e7us comme des caricatures pouss\u00e9es \u00e0 l&rsquo;absurde.<\/p>\n<p>C&rsquo;est le cas de Peggy et Sandy, les m\u00e8res est-allemandes de Hartz IV, de Sickroy et Fried, les pires magiciens du monde, et bien s\u00fbr de Dragan et Alder, les inventeurs de la Kanakcomedy, qui ont permis aux comiques cultes de Hesse de percer il y a un quart de si\u00e8cle. Des pointes satiriques s&rsquo;allument r\u00e9guli\u00e8rement, mais la plupart du temps, il s&rsquo;agit d&rsquo;une pure envie de faire des b\u00eatises, pr\u00e9sent\u00e9e avec une joie de jouer contagieuse.<\/p>\n<p>En ces temps de doigts d&rsquo;honneur toujours lev\u00e9s, d&rsquo;\u00e9toiles du genre et de politiquement correct, MUNDSTUHL continue de se moquer de tout et de tous, et le meilleur dans tout \u00e7a, c&rsquo;est qu&rsquo;on peut et qu&rsquo;on doit en rire de bon c\u0153ur.<\/p>\n<p>Les deux humoristes et podcasteurs Lars Niedereichholz et Ande Werner sont consid\u00e9r\u00e9s comme le duo comique le plus performant et le plus versatile d&rsquo;Allemagne. Dans leur nouveau programme, ils atteignent une densit\u00e9 de punch presque d\u00e9lirante.<br \/>\nMais attention ! Ce programme PEUT CONTENIR DES TRACES DE NOIX.<\/p>\n<p>\u00ab\u00a0Politiquement incorrect et hilarant\u00a0\u00bb. Westf\u00e4lische Allgemeine<br \/>\n\u00ab\u00a0MUNDSTUHL sont uniques !\u00a0\u00bb BZ<br \/>\n\u00ab\u00a0Applaudissements g\u00e9ants sous les larmes de rire !\u00a0\u00bb Journal BILD<br \/>\n\u00ab\u00a0L&rsquo;AC\/DC de la com\u00e9die ! A mourir de rire !\u00a0\u00bb SZ<\/p>\n<h3>Billetterie<\/h3>\n<p><a href=\"https:\/\/www.reservix.de\/tickets-mundstuhl-kann-spuren-von-nuessen-enthalten-in-radolfzell-milchwerk-am-29-9-2024\/e2139480\" target=\"_blank\" rel=\"noopener\">www.reservix.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le meilleur duo comique de l&rsquo;univers sort son prochain coup ! Et oui ! Ce sera plus dr\u00f4le que jamais. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[],"class_list":["post-80508","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mundstuhl - Peut contenir des traces de noix | Kultur Radolfzell<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mundstuhl - Peut contenir des traces de noix | Kultur Radolfzell\" \/>\n<meta property=\"og:description\" content=\"Le meilleur duo comique de l&rsquo;univers sort son prochain coup ! Et oui ! Ce sera plus dr\u00f4le que jamais. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/\" \/>\n<meta property=\"og:site_name\" content=\"Kultur Radolfzell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/\",\"url\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/\",\"name\":\"Mundstuhl - Peut contenir des traces de noix | Kultur Radolfzell\",\"isPartOf\":{\"@id\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/#website\"},\"datePublished\":\"2024-04-26T09:06:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/accueil\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltungen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mundstuhl &#8211; Peut contenir des traces de noix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/#website\",\"url\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/\",\"name\":\"Kultur Radolfzell\",\"description\":\"Landingpage\",\"publisher\":{\"@id\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/#organization\",\"name\":\"Kultur Radolfzell\",\"url\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kultur-radolfzell.de\/wp-content\/uploads\/2018\/11\/logo.png\",\"contentUrl\":\"https:\/\/kultur-radolfzell.de\/wp-content\/uploads\/2018\/11\/logo.png\",\"width\":500,\"height\":251,\"caption\":\"Kultur Radolfzell\"},\"image\":{\"@id\":\"https:\/\/staging.kultur-radolfzell.de\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mundstuhl - Peut contenir des traces de noix | Kultur Radolfzell","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Mundstuhl - Peut contenir des traces de noix | Kultur Radolfzell","og_description":"Le meilleur duo comique de l&rsquo;univers sort son prochain coup ! Et oui ! Ce sera plus dr\u00f4le que jamais. [&hellip;]","og_url":"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/","og_site_name":"Kultur Radolfzell","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/","url":"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/","name":"Mundstuhl - Peut contenir des traces de noix | Kultur Radolfzell","isPartOf":{"@id":"https:\/\/staging.kultur-radolfzell.de\/fr\/#website"},"datePublished":"2024-04-26T09:06:20+00:00","breadcrumb":{"@id":"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltung\/mundstuhl-peut-contenir-des-traces-de-noix-34\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/staging.kultur-radolfzell.de\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/staging.kultur-radolfzell.de\/fr\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Mundstuhl &#8211; Peut contenir des traces de noix"}]},{"@type":"WebSite","@id":"https:\/\/staging.kultur-radolfzell.de\/fr\/#website","url":"https:\/\/staging.kultur-radolfzell.de\/fr\/","name":"Kultur Radolfzell","description":"Landingpage","publisher":{"@id":"https:\/\/staging.kultur-radolfzell.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.kultur-radolfzell.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/staging.kultur-radolfzell.de\/fr\/#organization","name":"Kultur Radolfzell","url":"https:\/\/staging.kultur-radolfzell.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/staging.kultur-radolfzell.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/kultur-radolfzell.de\/wp-content\/uploads\/2018\/11\/logo.png","contentUrl":"https:\/\/kultur-radolfzell.de\/wp-content\/uploads\/2018\/11\/logo.png","width":500,"height":251,"caption":"Kultur Radolfzell"},"image":{"@id":"https:\/\/staging.kultur-radolfzell.de\/fr\/#\/schema\/logo\/image\/"}}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/staging.kultur-radolfzell.de\/fr\/wp-json\/wp\/v2\/tribe_events\/80508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.kultur-radolfzell.de\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/staging.kultur-radolfzell.de\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/staging.kultur-radolfzell.de\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/staging.kultur-radolfzell.de\/fr\/wp-json\/wp\/v2\/tribe_events\/80508\/revisions"}],"wp:attachment":[{"href":"https:\/\/staging.kultur-radolfzell.de\/fr\/wp-json\/wp\/v2\/media?parent=80508"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.kultur-radolfzell.de\/fr\/wp-json\/wp\/v2\/tags?post=80508"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/staging.kultur-radolfzell.de\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=80508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}